{"id":11751,"date":"2022-12-02T13:13:53","date_gmt":"2022-12-02T13:13:53","guid":{"rendered":"https:\/\/site-teste.uem.mz\/?p=11751"},"modified":"2023-02-27T06:59:40","modified_gmt":"2023-02-27T06:59:40","slug":"uem-e-kenmare-cooperam-na-pesquisa-e-investigacao","status":"publish","type":"post","link":"https:\/\/site-teste.uem.mz\/index.php\/2022\/12\/02\/uem-e-kenmare-cooperam-na-pesquisa-e-investigacao\/","title":{"rendered":"UEM e Kenmare cooperam na pesquisa e investiga\u00e7\u00e3o"},"content":{"rendered":"<p>A Universidade Eduardo Mondlane (UEM) e a Kenmare Moma Processing (Mauritius) assinaram esta sexta-feira, em Maputo, um memorando de entendimento, com vista a estabelecer rela\u00e7\u00f5es de coopera\u00e7\u00e3o nos dom\u00ednios de pesquisa e investiga\u00e7\u00e3o.<br>O memorando, rubricado pelo Reitor da UEM, Prof. Doutor Manuel Guilherme J\u00fanior e pelo director-geral da Kenmare, Engenheiro Higino Jamisse, visa igualmente garantir est\u00e1gios profissionais aos estudantes finalistas dos cursos de engenharia e ci\u00eancias.<br>Intervindo na ocasi\u00e3o, o Reitor da UEM disse que esta \u00e9 mais uma iniciativa que ir\u00e1 melhorar as condi\u00e7\u00f5es acad\u00e9micas e sociais dos estudantes, que poder\u00e3o p\u00f4r em pr\u00e1tica os seus conhecimentos atrav\u00e9s de est\u00e1gios profissionais numa das companhias de maior prest\u00edgio a operar no Pa\u00eds.<br>\u201cNos pr\u00f3ximos cinco anos, os estudantes poder\u00e3o realizar est\u00e1gios com os custos de desloca\u00e7\u00e3o, alojamento, alimenta\u00e7\u00e3o e equipamentos garantidos pelo nosso parceiro, Kenmare. Adicionalmente, atrav\u00e9s da iniciativa padrinho da UEM, ser\u00e1 poss\u00edvel prover financiamento para os candidatos \u00e0 forma\u00e7\u00e3o superior, que tenham dificuldades em financiar os seus estudos\u201d.<br>O Reitor acrescentou que, o memorando abarca tamb\u00e9m a realiza\u00e7\u00e3o conjunta de trabalhos de pesquisa e investiga\u00e7\u00e3o, no dom\u00ednio da engenharia, envolvendo estudantes e docentes da maior e mais antiga universidade do Pa\u00eds.<br>\u201cConsideramos que esta parceria contribuir\u00e1 na forma\u00e7\u00e3o de quadros virados para a explora\u00e7\u00e3o de recursos abundantes no Pa\u00eds e temos expectativas claras sobre o seu contributo para a constru\u00e7\u00e3o de uma sociedade mais competente, esclarecida, justa e inclusiva\u201d, referiu.<br>Por seu turno, o Director-geral da Kenmare afirmou que, o memorando constitui mais um acto de aproxima\u00e7\u00e3o entre o sector produtivo e a universidade, contribu\u00edndo para o desenvolvimento de ambas partes e, consequentemente, do Pa\u00eds.<br>\u201cProfissionais de qualidade formados pela UEM poder\u00e3o passar pela mineradora para aperfei\u00e7oar a pr\u00e1tica e tornarem-se bons profissionais. Um grupo de estudantes poder\u00e1 beneficiar de bolsas de estudos financiadas pela mineradora, incluindo est\u00e1gios profissionais\u201d.<br>Referiu que a Kenmare tem desafios que requerem o envolvimento de profissionais formados pela UEM em \u00e1reas como, metalurgia, expans\u00e3o de plantas e esp\u00e9cies em extin\u00e7\u00e3o no Pa\u00eds, bem como no uso de Tecnologias de Comunica\u00e7\u00e3o e Informa\u00e7\u00e3o, o que justifica a coopera\u00e7\u00e3o no dom\u00ednio da pesquisa e investiga\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Universidade Eduardo Mondlane (UEM) e a Kenmare Moma Processing (Mauritius) assinaram esta sexta-feira, em Maputo, um memorando de entendimento, com vista a estabelecer rela\u00e7\u00f5es de coopera\u00e7\u00e3o nos dom\u00ednios de pesquisa e investiga\u00e7\u00e3o.O memorando, rubricado pelo Reitor da UEM, Prof. &hellip; <\/p>\n","protected":false},"author":6,"featured_media":11752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/posts\/11751"}],"collection":[{"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/comments?post=11751"}],"version-history":[{"count":1,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/posts\/11751\/revisions"}],"predecessor-version":[{"id":11753,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/posts\/11751\/revisions\/11753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/media\/11752"}],"wp:attachment":[{"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/media?parent=11751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/categories?post=11751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site-teste.uem.mz\/index.php\/wp-json\/wp\/v2\/tags?post=11751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}